{"id":17361,"date":"2024-10-24T09:37:15","date_gmt":"2024-10-24T07:37:15","guid":{"rendered":"http:\/\/billigtrikots.com\/?post_type=product&#038;p=17361"},"modified":"2025-10-16T16:02:08","modified_gmt":"2025-10-16T14:02:08","slug":"herren-fussballtrikots-set-real-madrid-3rd-trikot-2023-2024-langarm-kurze-hosen","status":"publish","type":"product","link":"https:\/\/www.billigtrikotde.com\/it\/herren-fussballtrikots-set-real-madrid-3rd-trikot-2023-2024-langarm-kurze-hosen\/","title":{"rendered":"Set maglie calcio uomo Real Madrid 3a maglia 2023-2024 manica lunga + pantaloncini"},"content":{"rendered":"<p>Suggerimenti per la stampa: Se il nome e il numero dell'immagine sono esattamente quelli desiderati, non \u00e8 necessario inserirli nuovamente. In caso contrario, \u00e8 necessario inserire il nome e il numero desiderati.<\/p>\n<p>Consigli per il lavaggio: Si consiglia di lavare le magliette da calcio a mano. Se si desidera utilizzare la lavatrice, ricordarsi di capovolgere le magliette da calcio e poi lavarle. Riempire la macchina con acqua fredda e utilizzare un ciclo delicato per proteggere meglio i colori.<\/p>","protected":false},"excerpt":{"rendered":"<p>Consigli per la stampa: Se il nome e il numero sull'immagine corrispondono esattamente alle tue preferenze, non \u00e8 necessario reinserirli. In caso contrario, dovresti inserire il nome e il numero desiderati. Consigli per il lavaggio: si consiglia di lavare le maglie da calcio a mano. Se si desidera utilizzare la lavatrice, ricordarsi di girare le maglie da calcio [\u2026]<\/p>","protected":false},"featured_media":17402,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[45],"product_tag":[574,21,228,24,489,490,979,47],"class_list":{"0":"post-17361","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-real-madrid","7":"product_tag-fussballtrikot-deutschland","8":"product_tag-fussballtrikot-fuer-herren","9":"product_tag-guenstige-fussballtrikot","10":"product_tag-guenstiges-fussballtrikot","11":"product_tag-real-madrid-fussballtrikot","12":"product_tag-real-madrid-trikot","13":"product_tag-real-madrid-trikot-2024","14":"product_tag-real-madrid-trikots","16":"first","17":"instock","18":"shipping-taxable","19":"purchasable","20":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/www.billigtrikotde.com\/it\/wp-json\/wp\/v2\/product\/17361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.billigtrikotde.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.billigtrikotde.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/it\/wp-json\/wp\/v2\/comments?post=17361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/it\/wp-json\/wp\/v2\/media\/17402"}],"wp:attachment":[{"href":"https:\/\/www.billigtrikotde.com\/it\/wp-json\/wp\/v2\/media?parent=17361"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/it\/wp-json\/wp\/v2\/product_brand?post=17361"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/it\/wp-json\/wp\/v2\/product_cat?post=17361"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/it\/wp-json\/wp\/v2\/product_tag?post=17361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}