{"id":23510,"date":"2025-10-29T14:44:12","date_gmt":"2025-10-29T13:44:12","guid":{"rendered":"https:\/\/www.billigtrikotde.com\/?post_type=product&#038;p=23510"},"modified":"2025-10-29T14:45:34","modified_gmt":"2025-10-29T13:45:34","slug":"paris-saint-germain-marquinhos-5-heimtrikot-kinder-2025-26-fussball-trikotsatz","status":"publish","type":"product","link":"https:\/\/www.billigtrikotde.com\/es\/paris-saint-germain-marquinhos-5-heimtrikot-kinder-2025-26-fussball-trikotsatz\/","title":{"rendered":"Par\u00eds Saint-Germain Marquinhos #5 Camiseta de casa Ni\u00f1os 2025-26 Kit de f\u00fatbol"},"content":{"rendered":"<p>Consejos para la impresi\u00f3n: Si el nombre y el n\u00famero que aparecen en la imagen son exactamente los que desea, no es necesario que los vuelva a introducir. En caso contrario, deber\u00e1 introducir el nombre y el n\u00famero que desee.<\/p>\n<p>Consejos de lavado: Se recomienda lavar las camisetas de f\u00fatbol a mano. Si desea utilizar la lavadora, recuerde poner las camisetas de f\u00fatbol del rev\u00e9s y luego lavarlas. Llena la lavadora con agua fr\u00eda y utiliza un ciclo delicado para proteger mejor los colores.<\/p>","protected":false},"excerpt":{"rendered":"<p>Consejos para imprimir: si el nombre y el n\u00famero en la imagen coinciden exactamente con sus deseos, no es necesario que los vuelva a ingresar. Si no, debe ingresar el nombre y el n\u00famero que desea. Consejos para lavar: se recomienda lavar las camisetas de f\u00fatbol a mano. Si desea usar la lavadora, recuerde darle la vuelta a las camisetas de f\u00fatbol [\u2026]<\/p>","protected":false},"featured_media":23512,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[160],"product_tag":[1686,1685],"class_list":{"0":"post-23510","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-paris-saint-germain-kindertrikot","7":"product_tag-guenstige-marquinhos-trikot-kinder","8":"product_tag-marquinhos-trikot-kinder-kaufen","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/product\/23510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/comments?post=23510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/media\/23512"}],"wp:attachment":[{"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/media?parent=23510"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/product_brand?post=23510"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/product_cat?post=23510"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/product_tag?post=23510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}