{"id":14700,"date":"2024-10-24T07:09:29","date_gmt":"2024-10-24T05:09:29","guid":{"rendered":"http:\/\/billigtrikots.com\/?post_type=product&#038;p=14700"},"modified":"2024-10-24T07:12:09","modified_gmt":"2024-10-24T05:12:09","slug":"neueste-borussia-dortmund-auswaertstrikot-2023-24-kurzarm-mats-hummels-15","status":"publish","type":"product","link":"https:\/\/www.billigtrikotde.com\/es\/neueste-borussia-dortmund-auswaertstrikot-2023-24-kurzarm-mats-hummels-15\/","title":{"rendered":"Camiseta oficial Borussia Dortmund 2023-24 manga corta Mats Hummels 15"},"content":{"rendered":"<p>Consejos para la impresi\u00f3n: Si el nombre y el n\u00famero que aparecen en la imagen son exactamente los que desea, no es necesario que los vuelva a introducir. En caso contrario, deber\u00e1 introducir el nombre y el n\u00famero que desee.<\/p>\n<p>Consejos de lavado: Se recomienda lavar las camisetas de f\u00fatbol a mano. Si desea utilizar la lavadora, recuerde poner las camisetas de f\u00fatbol del rev\u00e9s y luego lavarlas. Llena la lavadora con agua fr\u00eda y utiliza un ciclo delicado para proteger mejor los colores.<\/p>","protected":false},"excerpt":{"rendered":"<p>Consejos para imprimir: si el nombre y el n\u00famero en la imagen coinciden exactamente con sus deseos, no es necesario que los vuelva a ingresar. Si no, debe ingresar el nombre y el n\u00famero que desea. Consejos para lavar: se recomienda lavar las camisetas de f\u00fatbol a mano. Si desea usar la lavadora, recuerde darle la vuelta a las camisetas de f\u00fatbol [\u2026]<\/p>","protected":false},"featured_media":14748,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[63],"product_tag":[20,65,649,650,66,574,21,23,24,789,790],"class_list":{"0":"post-14700","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-borussia-dortmund","7":"product_tag-coole-fussballtrikots","8":"product_tag-borussia-dortmund-trikots","9":"product_tag-bvb-borussia-dortmund-fussballtrikot","10":"product_tag-bvb-borussia-dortmund-trikot","11":"product_tag-bvb-trikots","12":"product_tag-fussballtrikot-deutschland","13":"product_tag-fussballtrikot-fuer-herren","14":"product_tag-fussballtrikot-kurzarm","15":"product_tag-guenstiges-fussballtrikot","16":"product_tag-mats-hummels-fussballtrikot","17":"product_tag-mats-hummels-trikot-fuer-kinder","19":"first","20":"instock","21":"shipping-taxable","22":"purchasable","23":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/product\/14700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/comments?post=14700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/media\/14748"}],"wp:attachment":[{"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/media?parent=14700"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/product_brand?post=14700"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/product_cat?post=14700"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.billigtrikotde.com\/es\/wp-json\/wp\/v2\/product_tag?post=14700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}